{"id":2669,"date":"2013-07-18T08:14:33","date_gmt":"2013-07-18T07:14:33","guid":{"rendered":"http:\/\/www.dolanzarote.com\/?p=2669"},"modified":"2013-07-18T08:14:33","modified_gmt":"2013-07-18T07:14:33","slug":"el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta","status":"publish","type":"post","link":"https:\/\/dolanzarote.com\/fr\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/","title":{"rendered":"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta"},"content":{"rendered":"<p>El Instituto Canario de Calidad Agroalimentaria (ICCA) y la empresa de restauraci\u00f3n en ruta SSP Espa\u00f1a llevar\u00e1n a cabo hoy jueves 18 de julio, con la colaboraci\u00f3n del Consejo Regulador de la Denominaci\u00f3n de Origen \u201cVinos de Lanzarote\u201d, catas expr\u00e9s de vinos lanzarote\u00f1os en el aeropuerto de Guacimeta con el objetivo de promover el conocimiento y consumo de los principales caldos de la Isla.<\/p>\n<p>Las catas expr\u00e9s, que tendr\u00e1n lugar entre las 11.30 y las 13.30 horas en el \u00e1rea de \u2018food court\u2019 de SSP en el aeropuerto lanzarote\u00f1o, se desarrollar\u00e1n en seis sesiones de un cuarto de hora de duraci\u00f3n cada una para 20 personas. En ellas se degustar\u00e1n algunos de los vinos mejor valorados en el certamen oficial Agrocanarias 2013 organizado por el ICCA y celebrado recientemente.<\/p>\n<p>De esta forma, m\u00e1s de 240 pasajeros de vuelos nacionales e internacionales podr\u00e1n asistir a las catas expr\u00e9s, que estar\u00e1n guiadas en espa\u00f1ol e ingl\u00e9s por expertos catadores. En este sentido, las sesiones cuentan con la colaboraci\u00f3n del Consejo Regulador, cuyo personal trabajar\u00e1 para su realizaci\u00f3n.<\/p>\n<p>El objetivo de esta iniciativa es ofrecer a los visitantes de las Islas unas breves pinceladas sobre las singularidades de la viticultura isle\u00f1a y las cualidades de los vinos canarios. En definitiva, se trata de que los turistas consuman estos productos y se lleven un buen recuerdo de ellos, convirti\u00e9ndose as\u00ed en embajadores de los mismos en sus pa\u00edses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Canario de Calidad Agroalimentaria (ICCA) y la empresa de restauraci\u00f3n en ruta SSP Espa\u00f1a llevar\u00e1n a cabo hoy jueves 18 de julio, con la colaboraci\u00f3n del Consejo Regulador de la Denominaci\u00f3n de Origen \u201cVinos de Lanzarote\u201d, catas expr\u00e9s de vinos lanzarote\u00f1os en el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2669","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta - D.O. Lanzarote<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta - D.O. Lanzarote\" \/>\n<meta property=\"og:description\" content=\"El Instituto Canario de Calidad Agroalimentaria (ICCA) y la empresa de restauraci\u00f3n en ruta SSP Espa\u00f1a llevar\u00e1n a cabo hoy jueves 18 de julio, con la colaboraci\u00f3n del Consejo Regulador de la Denominaci\u00f3n de Origen \u201cVinos de Lanzarote\u201d, catas expr\u00e9s de vinos lanzarote\u00f1os en el...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/\" \/>\n<meta property=\"og:site_name\" content=\"D.O. Lanzarote\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-18T07:14:33+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#\\\/schema\\\/person\\\/8e23003ed0a8a9cac9add89729707ff6\"},\"headline\":\"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta\",\"datePublished\":\"2013-07-18T07:14:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\\\/\"},\"wordCount\":281,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\\\/\",\"url\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\\\/\",\"name\":\"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta - D.O. Lanzarote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#website\"},\"datePublished\":\"2013-07-18T07:14:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#\\\/schema\\\/person\\\/8e23003ed0a8a9cac9add89729707ff6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/dolanzarote.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/\",\"name\":\"D.O. Lanzarote\",\"description\":\"Vinos de Lanzarote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#\\\/schema\\\/person\\\/8e23003ed0a8a9cac9add89729707ff6\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/dolanzarote.com\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta - D.O. Lanzarote","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/","og_locale":"fr_FR","og_type":"article","og_title":"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta - D.O. Lanzarote","og_description":"El Instituto Canario de Calidad Agroalimentaria (ICCA) y la empresa de restauraci\u00f3n en ruta SSP Espa\u00f1a llevar\u00e1n a cabo hoy jueves 18 de julio, con la colaboraci\u00f3n del Consejo Regulador de la Denominaci\u00f3n de Origen \u201cVinos de Lanzarote\u201d, catas expr\u00e9s de vinos lanzarote\u00f1os en el...","og_url":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/","og_site_name":"D.O. Lanzarote","article_published_time":"2013-07-18T07:14:33+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/#article","isPartOf":{"@id":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/"},"author":{"name":"admin","@id":"https:\/\/dolanzarote.com\/de\/#\/schema\/person\/8e23003ed0a8a9cac9add89729707ff6"},"headline":"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta","datePublished":"2013-07-18T07:14:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/"},"wordCount":281,"articleSection":["Noticias"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/","url":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/","name":"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta - D.O. Lanzarote","isPartOf":{"@id":"https:\/\/dolanzarote.com\/de\/#website"},"datePublished":"2013-07-18T07:14:33+00:00","author":{"@id":"https:\/\/dolanzarote.com\/de\/#\/schema\/person\/8e23003ed0a8a9cac9add89729707ff6"},"breadcrumb":{"@id":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dolanzarote.com\/de\/el-consejo-regulador-colabora-en-las-catas-expres-de-vinos-denominacion-de-origen-lanzarote-que-se-llevaran-a-cabo-hoy-jueves-en-el-aeropuerto-de-guacimeta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dolanzarote.com\/"},{"@type":"ListItem","position":2,"name":"El Consejo Regulador colabora en las catas expr\u00e9s de Vinos Denominaci\u00f3n de Origen Lanzarote que se llevar\u00e1n a cabo hoy jueves en el Aeropuerto de Guacimeta"}]},{"@type":"WebSite","@id":"https:\/\/dolanzarote.com\/de\/#website","url":"https:\/\/dolanzarote.com\/de\/","name":"D.O. Lanzarote","description":"Vinos de Lanzarote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dolanzarote.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/dolanzarote.com\/de\/#\/schema\/person\/8e23003ed0a8a9cac9add89729707ff6","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/dolanzarote.com\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/posts\/2669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/comments?post=2669"}],"version-history":[{"count":0,"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/posts\/2669\/revisions"}],"wp:attachment":[{"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/media?parent=2669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/categories?post=2669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dolanzarote.com\/fr\/wp-json\/wp\/v2\/tags?post=2669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}