{"id":2614,"date":"2013-06-20T13:21:10","date_gmt":"2013-06-20T12:21:10","guid":{"rendered":"http:\/\/www.dolanzarote.com\/?p=2614"},"modified":"2013-06-20T13:21:10","modified_gmt":"2013-06-20T12:21:10","slug":"el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco","status":"publish","type":"post","link":"https:\/\/dolanzarote.com\/en\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/","title":{"rendered":"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco"},"content":{"rendered":"<p>El Malvas\u00eda Moscatel 2012 de Bodegas Reymar ha sido galardonado con una medalla de oro en la XXVII Edici\u00f3n Nacional de los Premios Baco Cosecha 2012, organizados por la Uni\u00f3n Espa\u00f1ola de Catadores y avalados por el Ministerio de Agricultura, Alimentaci\u00f3n y Medio Ambiente. Este concurso est\u00e1 destinado a los vinos j\u00f3venes, donde alrededor de 500 muestras diferentes concurrieron en este evento, y en el que intervinieron 60 jueces de la Uni\u00f3n Espa\u00f1ola de Catadores.<\/p>\n<p>\u00a0<a href=\"https:\/\/dolanzarote.com\/wp-content\/uploads\/2013\/06\/LOGO-REYMAR.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2615\" alt=\"LOGO REYMAR\" src=\"https:\/\/dolanzarote.com\/wp-content\/uploads\/2013\/06\/LOGO-REYMAR-300x138.jpg\" width=\"300\" height=\"138\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Malvas\u00eda Moscatel 2012 de Bodegas Reymar ha sido galardonado con una medalla de oro en la XXVII Edici\u00f3n Nacional de los Premios Baco Cosecha 2012, organizados por la Uni\u00f3n Espa\u00f1ola de Catadores y avalados por el Ministerio de Agricultura, Alimentaci\u00f3n y Medio Ambiente. Este&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2614","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco - D.O. Lanzarote<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco - D.O. Lanzarote\" \/>\n<meta property=\"og:description\" content=\"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar ha sido galardonado con una medalla de oro en la XXVII Edici\u00f3n Nacional de los Premios Baco Cosecha 2012, organizados por la Uni\u00f3n Espa\u00f1ola de Catadores y avalados por el Ministerio de Agricultura, Alimentaci\u00f3n y Medio Ambiente. Este...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/\" \/>\n<meta property=\"og:site_name\" content=\"D.O. Lanzarote\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-20T12:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dolanzarote.com\/wp-content\/uploads\/2013\/06\/LOGO-REYMAR-300x138.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#\\\/schema\\\/person\\\/8e23003ed0a8a9cac9add89729707ff6\"},\"headline\":\"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco\",\"datePublished\":\"2013-06-20T12:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/\"},\"wordCount\":93,\"image\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dolanzarote.com\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/LOGO-REYMAR-300x138.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/\",\"url\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/\",\"name\":\"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco - D.O. Lanzarote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dolanzarote.com\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/LOGO-REYMAR-300x138.jpg\",\"datePublished\":\"2013-06-20T12:21:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#\\\/schema\\\/person\\\/8e23003ed0a8a9cac9add89729707ff6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dolanzarote.com\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/LOGO-REYMAR-300x138.jpg\",\"contentUrl\":\"https:\\\/\\\/dolanzarote.com\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/LOGO-REYMAR-300x138.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/dolanzarote.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/\",\"name\":\"D.O. Lanzarote\",\"description\":\"Vinos de Lanzarote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dolanzarote.com\\\/de\\\/#\\\/schema\\\/person\\\/8e23003ed0a8a9cac9add89729707ff6\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/dolanzarote.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco - D.O. Lanzarote","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/","og_locale":"en_US","og_type":"article","og_title":"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco - D.O. Lanzarote","og_description":"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar ha sido galardonado con una medalla de oro en la XXVII Edici\u00f3n Nacional de los Premios Baco Cosecha 2012, organizados por la Uni\u00f3n Espa\u00f1ola de Catadores y avalados por el Ministerio de Agricultura, Alimentaci\u00f3n y Medio Ambiente. Este...","og_url":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/","og_site_name":"D.O. Lanzarote","article_published_time":"2013-06-20T12:21:10+00:00","og_image":[{"url":"https:\/\/dolanzarote.com\/wp-content\/uploads\/2013\/06\/LOGO-REYMAR-300x138.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/#article","isPartOf":{"@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/"},"author":{"name":"admin","@id":"https:\/\/dolanzarote.com\/de\/#\/schema\/person\/8e23003ed0a8a9cac9add89729707ff6"},"headline":"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco","datePublished":"2013-06-20T12:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/"},"wordCount":93,"image":{"@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/#primaryimage"},"thumbnailUrl":"https:\/\/dolanzarote.com\/wp-content\/uploads\/2013\/06\/LOGO-REYMAR-300x138.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/","url":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/","name":"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco - D.O. Lanzarote","isPartOf":{"@id":"https:\/\/dolanzarote.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/#primaryimage"},"image":{"@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/#primaryimage"},"thumbnailUrl":"https:\/\/dolanzarote.com\/wp-content\/uploads\/2013\/06\/LOGO-REYMAR-300x138.jpg","datePublished":"2013-06-20T12:21:10+00:00","author":{"@id":"https:\/\/dolanzarote.com\/de\/#\/schema\/person\/8e23003ed0a8a9cac9add89729707ff6"},"breadcrumb":{"@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/#primaryimage","url":"https:\/\/dolanzarote.com\/wp-content\/uploads\/2013\/06\/LOGO-REYMAR-300x138.jpg","contentUrl":"https:\/\/dolanzarote.com\/wp-content\/uploads\/2013\/06\/LOGO-REYMAR-300x138.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dolanzarote.com\/de\/el-malvasia-moscatel-2012-de-bodegas-reymar-medalla-de-oro-en-los-premios-baco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/dolanzarote.com\/"},{"@type":"ListItem","position":2,"name":"El Malvas\u00eda Moscatel 2012 de Bodegas Reymar, medalla de oro en los Premios Baco"}]},{"@type":"WebSite","@id":"https:\/\/dolanzarote.com\/de\/#website","url":"https:\/\/dolanzarote.com\/de\/","name":"D.O. Lanzarote","description":"Vinos de Lanzarote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dolanzarote.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/dolanzarote.com\/de\/#\/schema\/person\/8e23003ed0a8a9cac9add89729707ff6","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e05d7a1350716a6e7082ca7e5b63b6305cb7327fa88c38fe95e02ca761cf9753?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/dolanzarote.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/posts\/2614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/comments?post=2614"}],"version-history":[{"count":0,"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/posts\/2614\/revisions"}],"wp:attachment":[{"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/media?parent=2614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/categories?post=2614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dolanzarote.com\/en\/wp-json\/wp\/v2\/tags?post=2614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}